{"id":282730,"date":"2022-06-12T23:28:24","date_gmt":"2022-06-13T03:28:24","guid":{"rendered":"https:\/\/seedyourhead.com\/boston\/?p=282730"},"modified":"2025-02-12T15:47:15","modified_gmt":"2025-02-12T20:47:15","slug":"fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2","status":"publish","type":"post","link":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/","title":{"rendered":"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics"},"content":{"rendered":"<div class=\"instagram_image\">\n<img loading=\"lazy\" decoding=\"async\" width=\"1166\" height=\"2070\" alt=\"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics\" src=\"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1.jpg\" class=\"video wp-image-282731\" srcset=\"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1.jpg 1166w, https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1-980x1740.jpg 980w, https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1-480x852.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1166px, 100vw\" \/>\n<\/div>\n<p class=\"instagram_headline\">Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics<\/p>\n<div style=\"width: 620px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-282730-1\" width=\"620\" height=\"620\" poster=\"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1.jpg\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/AQNEqGjqTK1TsGc039EBWlAI8bP5yLUAHc7bU9z_mvcQswMsF4XNWtPdUKzQHErDLpyvsOF1qLHrYPjelxN8-is222QMtNFjY5kKW0E.mp4?_=1\" \/><a href=\"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/AQNEqGjqTK1TsGc039EBWlAI8bP5yLUAHc7bU9z_mvcQswMsF4XNWtPdUKzQHErDLpyvsOF1qLHrYPjelxN8-is222QMtNFjY5kKW0E.mp4\">https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/AQNEqGjqTK1TsGc039EBWlAI8bP5yLUAHc7bU9z_mvcQswMsF4XNWtPdUKzQHErDLpyvsOF1qLHrYPjelxN8-is222QMtNFjY5kKW0E.mp4<\/a><\/video><\/div>\n<p style=\"margin-top: 25px\"><a href=\"https:\/\/www.instagram.com\/reel\/CeuvNokDsVy\/\" Target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">View on Instagram<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics<\/p>\n","protected":false},"author":4117,"featured_media":282731,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[25],"tags":[],"class_list":["post-282730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-instagram"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/AQNEqGjqTK1TsGc039EBWlAI8bP5yLUAHc7bU9z_mvcQswMsF4XNWtPdUKzQHErDLpyvsOF1qLHrYPjelxN8-is222QMtNFjY5kKW0E.mp4 View on Instagram\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Seed Your Head\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Seed\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics | Seed, Boston MA\" \/>\n\t\t<meta property=\"og:description\" content=\"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/AQNEqGjqTK1TsGc039EBWlAI8bP5yLUAHc7bU9z_mvcQswMsF4XNWtPdUKzQHErDLpyvsOF1qLHrYPjelxN8-is222QMtNFjY5kKW0E.mp4 View on Instagram\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1166\" \/>\n\t\t<meta property=\"og:image:height\" content=\"2070\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-06-13T03:28:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-02-12T20:47:15+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Seedyourhead\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@Seedyourhead\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics | Seed, Boston MA\" \/>\n\t\t<meta name=\"twitter:description\" content=\"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/AQNEqGjqTK1TsGc039EBWlAI8bP5yLUAHc7bU9z_mvcQswMsF4XNWtPdUKzQHErDLpyvsOF1qLHrYPjelxN8-is222QMtNFjY5kKW0E.mp4 View on Instagram\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#article\",\"name\":\"Fun Fun! We love our vendors \\ufe0f\\ud83e\\udde1@rev_clinics | Seed, Boston MA\",\"headline\":\"Fun Fun! We love our vendors \\ufe0f\\ud83e\\udde1@rev_clinics\",\"author\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/author\\\/wluz\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/06\\\/287734530_350241493912175_2598913462927309799_n-1.jpg\",\"width\":1166,\"height\":2070,\"caption\":\"Fun Fun! We love our vendors \\ufe0f\\ud83e\\udde1@rev_clinics\"},\"datePublished\":\"2022-06-12T23:28:24-04:00\",\"dateModified\":\"2025-02-12T15:47:15-05:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#webpage\"},\"articleSection\":\"Instagram\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seedyourhead.com\\\/boston\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/category\\\/instagram\\\/#listItem\",\"name\":\"Instagram\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/category\\\/instagram\\\/#listItem\",\"position\":2,\"name\":\"Instagram\",\"item\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/category\\\/instagram\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#listItem\",\"name\":\"Fun Fun! We love our vendors \\ufe0f\\ud83e\\udde1@rev_clinics\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#listItem\",\"position\":3,\"name\":\"Fun Fun! We love our vendors \\ufe0f\\ud83e\\udde1@rev_clinics\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/category\\\/instagram\\\/#listItem\",\"name\":\"Instagram\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/#organization\",\"name\":\"SEED\",\"description\":\"Cannabis Dispensary\",\"url\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/\",\"telephone\":\"+16175535922\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2021\\\/01\\\/seed-community-cannabis-market-logo.png\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/seedyourhead\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/seedyourhead\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCX1wxY1ct_QZbwq8c-1_Igw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/seedyourhead\\\/\"],\"address\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"401A Centre Street\",\"postalCode\":\"02130\",\"addressLocality\":\"Boston\",\"addressRegion\":\"MA\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/author\\\/wluz\\\/#author\",\"url\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/author\\\/wluz\\\/\",\"name\":\"Seed Your Head\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dc71b5478315d9bb98a786d7b907534613af1e25c7da2a9d5fdd148a1798e2e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Seed Your Head\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#webpage\",\"url\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/\",\"name\":\"Fun Fun! We love our vendors \\ufe0f\\ud83e\\udde1@rev_clinics | Seed, Boston MA\",\"description\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/06\\\/AQNEqGjqTK1TsGc039EBWlAI8bP5yLUAHc7bU9z_mvcQswMsF4XNWtPdUKzQHErDLpyvsOF1qLHrYPjelxN8-is222QMtNFjY5kKW0E.mp4 View on Instagram\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/author\\\/wluz\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/author\\\/wluz\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/06\\\/287734530_350241493912175_2598913462927309799_n-1.jpg\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#mainImage\",\"width\":1166,\"height\":2070,\"caption\":\"Fun Fun! We love our vendors \\ufe0f\\ud83e\\udde1@rev_clinics\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/recreational-cannabis-dispensary-boston-ma\\\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\\\/#mainImage\"},\"datePublished\":\"2022-06-12T23:28:24-04:00\",\"dateModified\":\"2025-02-12T15:47:15-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/#website\",\"url\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/\",\"name\":\"Seed\",\"alternateName\":\"Seed: Recreational Adult Use Cannabis Marijuana Dispensary Boston\",\"description\":\"Cannabis Dispensary\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/seedyourhead.com\\\/boston\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics | Seed, Boston MA<\/title>\n\n","aioseo_head_json":{"title":"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics | Seed, Boston MA","description":"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/AQNEqGjqTK1TsGc039EBWlAI8bP5yLUAHc7bU9z_mvcQswMsF4XNWtPdUKzQHErDLpyvsOF1qLHrYPjelxN8-is222QMtNFjY5kKW0E.mp4 View on Instagram","canonical_url":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#article","name":"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics | Seed, Boston MA","headline":"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics","author":{"@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/author\/wluz\/#author"},"publisher":{"@id":"https:\/\/seedyourhead.com\/boston\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1.jpg","width":1166,"height":2070,"caption":"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics"},"datePublished":"2022-06-12T23:28:24-04:00","dateModified":"2025-02-12T15:47:15-05:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#webpage"},"isPartOf":{"@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#webpage"},"articleSection":"Instagram"},{"@type":"BreadcrumbList","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/seedyourhead.com\/boston#listItem","position":1,"name":"Home","item":"https:\/\/seedyourhead.com\/boston","nextItem":{"@type":"ListItem","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/category\/instagram\/#listItem","name":"Instagram"}},{"@type":"ListItem","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/category\/instagram\/#listItem","position":2,"name":"Instagram","item":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/category\/instagram\/","nextItem":{"@type":"ListItem","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#listItem","name":"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics"},"previousItem":{"@type":"ListItem","@id":"https:\/\/seedyourhead.com\/boston#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#listItem","position":3,"name":"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics","previousItem":{"@type":"ListItem","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/category\/instagram\/#listItem","name":"Instagram"}}]},{"@type":"Organization","@id":"https:\/\/seedyourhead.com\/boston\/#organization","name":"SEED","description":"Cannabis Dispensary","url":"https:\/\/seedyourhead.com\/boston\/","telephone":"+16175535922","logo":{"@type":"ImageObject","url":"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/9\/2021\/01\/seed-community-cannabis-market-logo.png","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#organizationLogo"},"image":{"@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/seedyourhead\/","https:\/\/www.pinterest.com\/seedyourhead\/","https:\/\/www.youtube.com\/channel\/UCX1wxY1ct_QZbwq8c-1_Igw","https:\/\/www.linkedin.com\/company\/seedyourhead\/"],"address":{"@id":"https:\/\/seedyourhead.com\/boston\/#postaladdress","@type":"PostalAddress","streetAddress":"401A Centre Street","postalCode":"02130","addressLocality":"Boston","addressRegion":"MA"}},{"@type":"Person","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/author\/wluz\/#author","url":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/author\/wluz\/","name":"Seed Your Head","image":{"@type":"ImageObject","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4dc71b5478315d9bb98a786d7b907534613af1e25c7da2a9d5fdd148a1798e2e?s=96&d=mm&r=g","width":96,"height":96,"caption":"Seed Your Head"}},{"@type":"WebPage","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#webpage","url":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/","name":"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics | Seed, Boston MA","description":"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/AQNEqGjqTK1TsGc039EBWlAI8bP5yLUAHc7bU9z_mvcQswMsF4XNWtPdUKzQHErDLpyvsOF1qLHrYPjelxN8-is222QMtNFjY5kKW0E.mp4 View on Instagram","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/seedyourhead.com\/boston\/#website"},"breadcrumb":{"@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#breadcrumblist"},"author":{"@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/author\/wluz\/#author"},"creator":{"@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/author\/wluz\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1.jpg","@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#mainImage","width":1166,"height":2070,"caption":"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics"},"primaryImageOfPage":{"@id":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/#mainImage"},"datePublished":"2022-06-12T23:28:24-04:00","dateModified":"2025-02-12T15:47:15-05:00"},{"@type":"WebSite","@id":"https:\/\/seedyourhead.com\/boston\/#website","url":"https:\/\/seedyourhead.com\/boston\/","name":"Seed","alternateName":"Seed: Recreational Adult Use Cannabis Marijuana Dispensary Boston","description":"Cannabis Dispensary","inLanguage":"en-US","publisher":{"@id":"https:\/\/seedyourhead.com\/boston\/#organization"}}]},"og:locale":"en_US","og:site_name":"Seed","og:type":"article","og:title":"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics | Seed, Boston MA","og:description":"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/AQNEqGjqTK1TsGc039EBWlAI8bP5yLUAHc7bU9z_mvcQswMsF4XNWtPdUKzQHErDLpyvsOF1qLHrYPjelxN8-is222QMtNFjY5kKW0E.mp4 View on Instagram","og:url":"https:\/\/seedyourhead.com\/boston\/recreational-cannabis-dispensary-boston-ma\/fun-fun-we-love-our-vendors-%ef%b8%8f%f0%9f%a7%a1rev_clinics-2\/","og:image":"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1.jpg","og:image:secure_url":"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1.jpg","og:image:width":1166,"og:image:height":2070,"article:published_time":"2022-06-13T03:28:24+00:00","article:modified_time":"2025-02-12T20:47:15+00:00","article:publisher":"https:\/\/www.facebook.com\/Seedyourhead","twitter:card":"summary_large_image","twitter:site":"@Seedyourhead","twitter:title":"Fun Fun! We love our vendors \ufe0f\ud83e\udde1@rev_clinics | Seed, Boston MA","twitter:description":"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/AQNEqGjqTK1TsGc039EBWlAI8bP5yLUAHc7bU9z_mvcQswMsF4XNWtPdUKzQHErDLpyvsOF1qLHrYPjelxN8-is222QMtNFjY5kKW0E.mp4 View on Instagram","twitter:image":"https:\/\/seedyourhead.com\/boston\/wp-content\/uploads\/sites\/2\/2022\/06\/287734530_350241493912175_2598913462927309799_n-1.jpg"},"aioseo_meta_data":{"post_id":"282730","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-21 14:33:35","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2025-02-12 23:15:02","updated":"2026-05-21 14:33:35"},"_links":{"self":[{"href":"https:\/\/seedyourhead.com\/boston\/wp-json\/wp\/v2\/posts\/282730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seedyourhead.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seedyourhead.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seedyourhead.com\/boston\/wp-json\/wp\/v2\/users\/4117"}],"replies":[{"embeddable":true,"href":"https:\/\/seedyourhead.com\/boston\/wp-json\/wp\/v2\/comments?post=282730"}],"version-history":[{"count":0,"href":"https:\/\/seedyourhead.com\/boston\/wp-json\/wp\/v2\/posts\/282730\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seedyourhead.com\/boston\/wp-json\/wp\/v2\/media\/282731"}],"wp:attachment":[{"href":"https:\/\/seedyourhead.com\/boston\/wp-json\/wp\/v2\/media?parent=282730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seedyourhead.com\/boston\/wp-json\/wp\/v2\/categories?post=282730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seedyourhead.com\/boston\/wp-json\/wp\/v2\/tags?post=282730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}